{"id":920,"date":"2023-08-17T22:10:00","date_gmt":"2023-08-17T20:10:00","guid":{"rendered":"https:\/\/chroniken.whenua.at\/del-nolo\/?p=920"},"modified":"2025-08-08T22:32:54","modified_gmt":"2025-08-08T20:32:54","slug":"kind-und-kegel","status":"publish","type":"post","link":"https:\/\/chroniken.whenua.at\/del-nolo\/kind-und-kegel\/","title":{"rendered":"Kind und Kegel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Unter dem Feldpavillon der Linsar Garde steckten bereits einige der wichtigsten Strategen der vier Quarter ihre K\u00f6pfe zusammen. Ich betrat das gut befestigte Lager mit meiner kleinen Tochter Lucy auf dem Arm. Sie konnte bereits gehen, aber bei derartigen Menschenansammlungen verga\u00df sie das nur zu gern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir setzten uns an den langen Tisch, auf der die Karte Whenuas ausgebreitet lag. Darauf standen kleine Figuren, welche die unterschiedlichen Truppen darstellten. Sofort griff Lucy danach und brachte alles durcheinander. Sie verwendete die Figuren wie Kegel ihres Lieblingsspiels &#8222;Siedler geh heim&#8220; und lie\u00df sie \u00fcber die Karte spazieren. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch das viel kaum auf. Die anderen debattierten \u00fcber die verschiedenen M\u00f6glichkeiten Ostarium zur\u00fcckzugewinnen und welche Fallen Fly ihnen wohl stellen k\u00f6nnte. Ich trug nicht wirklich etwas bei. Sie schienen alles im Griff zu haben.<br><br>Das war mir nur Recht. Mich besch\u00e4ftigte sowieso meine eigen Unternehmung schon ausreichend. In nur einem knappen Monat w\u00fcrde ich mit einem Trupp der Nachricht von Malika nachgehen. Sie braucht dringend meine Hilfe gegen Lucius und seine Untoten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter dem Feldpavillon der Linsar Garde steckten bereits einige der wichtigsten Strategen der vier Quarter ihre K\u00f6pfe zusammen. Ich betrat das gut befestigte Lager mit meiner kleinen Tochter Lucy auf dem Arm. Sie konnte bereits gehen, aber bei derartigen Menschenansammlungen verga\u00df sie das nur zu gern. Wir setzten uns an&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/chroniken.whenua.at\/del-nolo\/kind-und-kegel\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"ppma_author":[29],"class_list":["post-920","post","type-post","status-publish","format-standard","hentry","category-tdt-223"],"authors":[{"term_id":29,"user_id":2,"is_guest":0,"slug":"lyanna","display_name":"Lyanna del Nolo","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/69d1d8256126cbedb37057beca5363303685a1f9d047a9b7d31bcf99f00788c5?s=96&d=mm&r=g","author_category":"","first_name":"Lyanna","last_name":"del Nolo","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/comments?post=920"}],"version-history":[{"count":1,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/920\/revisions"}],"predecessor-version":[{"id":925,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/920\/revisions\/925"}],"wp:attachment":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/media?parent=920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/categories?post=920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/tags?post=920"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/ppma_author?post=920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}