{"id":707,"date":"2015-05-09T12:50:00","date_gmt":"2015-05-09T10:50:00","guid":{"rendered":"https:\/\/chroniken.whenua.at\/del-nolo\/?p=707"},"modified":"2025-08-08T23:28:13","modified_gmt":"2025-08-08T21:28:13","slug":"muelsa-spricht","status":"publish","type":"post","link":"https:\/\/chroniken.whenua.at\/del-nolo\/muelsa-spricht\/","title":{"rendered":"Muel&#8217;Sa spricht"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Schlacht war vorbei. Eine Generation tot. So viele Verletzte. Lucius war zum hohen Untoten aufgestiegen und verschwand mit den Resten seines Gefolges. Doch es war noch nicht vorbei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcber uns hinweg erschallte Muel&#8217;Sas Stimme \u2013 ich konnte sie fast k\u00f6rperlich sp\u00fcren: &#8222;Und euch Verr\u00e4tern b\u00fcrde ich die Strafe des Lebens auf! Ihr sollt jeden Schmerz, welchem ihr in eurem Dasein als Untoter entgangen seid, nun doch sp\u00fcren.&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seine Worte waren an die untoten Helden, die sich meiner Sache angeschlossen hatten, gerichtet. Aruad und &#8222;Sebi&#8220; gingen auch sogleich schreiend zu Boden. An ihrem entr\u00fcckten Blick konnte ich das Ausma\u00df ihrer Qualen sehen. Unsere Heiler st\u00fcrmten heran; es dauerte eine Ewigkeit, doch schlussendlich konnten die beiden gerettet werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Lichtblick: Sie waren wieder Menschen, wieder Teil der Lebenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ein kleiner Trost.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schlacht war vorbei. Eine Generation tot. So viele Verletzte. Lucius war zum hohen Untoten aufgestiegen und verschwand mit den Resten seines Gefolges. Doch es war noch nicht vorbei. \u00dcber uns hinweg erschallte Muel&#8217;Sas Stimme \u2013 ich konnte sie fast k\u00f6rperlich sp\u00fcren: &#8222;Und euch Verr\u00e4tern b\u00fcrde ich die Strafe des&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/chroniken.whenua.at\/del-nolo\/muelsa-spricht\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"ppma_author":[29],"class_list":["post-707","post","type-post","status-publish","format-standard","hentry","category-schlachtensang-1-215"],"authors":[{"term_id":29,"user_id":2,"is_guest":0,"slug":"lyanna","display_name":"Lyanna del Nolo","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/69d1d8256126cbedb37057beca5363303685a1f9d047a9b7d31bcf99f00788c5?s=96&d=mm&r=g","author_category":"","first_name":"Lyanna","last_name":"del Nolo","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/comments?post=707"}],"version-history":[{"count":3,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/707\/revisions"}],"predecessor-version":[{"id":934,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/707\/revisions\/934"}],"wp:attachment":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/categories?post=707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/tags?post=707"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/ppma_author?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}