{"id":1038,"date":"2017-05-19T23:08:00","date_gmt":"2017-05-19T21:08:00","guid":{"rendered":"https:\/\/chroniken.whenua.at\/del-nolo\/?p=1038"},"modified":"2025-08-12T23:21:31","modified_gmt":"2025-08-12T21:21:31","slug":"spinnen-und-ihre-maenner","status":"publish","type":"post","link":"https:\/\/chroniken.whenua.at\/del-nolo\/spinnen-und-ihre-maenner\/","title":{"rendered":"Spinnen und ihre M\u00e4nner"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Ich bin Lyanna del Nolo, Protecta von Melvis. Warum nur f\u00fchl ich mich trotzdem gerade so klein?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf hohen Hacken tritt mir LiNeer w\u00fcrdevoll entgegen und betrachtet mich argw\u00f6hnisch. Gnak Prak zum Dank, stand ich nun nicht mit leeren H\u00e4nden da. LiNeer nahm das Geschenk an, doch brach das keines Wegs die k\u00fchle Distanz die ich zwischen uns sp\u00fchrte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir tauschten uns vor allem dar\u00fcber aus, dass der Untot ein gemeinsamer Feind war und wie sehr ein untotes Dasein wider der Natur w\u00e4re. LiNeer versicherte mir, das Haus Alea\u2019n\u2019dar w\u00fcrde mit mir ziehen, wann immer ich gegen so einen Feind antreten m\u00fcsste. Ich hatte wohl doch wertvolle Verb\u00fcndete gefunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es schien so, dass dies unter anderem daran lag, dass ich eine Frau war. Die Drow f\u00fchrten ein Matriarchat. Der Mann, welcher LiNeer und mich die ganze Zeit \u00fcber mit Getr\u00e4nken versorgte, wirkte sehr verschreckt. Fast, als f\u00fcrchtete er jeden Moment verschlungen zu werden, wie das weibliche Spinnentiere so machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Schon etwas unheimlich.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin Lyanna del Nolo, Protecta von Melvis. Warum nur f\u00fchl ich mich trotzdem gerade so klein? Auf hohen Hacken tritt mir LiNeer w\u00fcrdevoll entgegen und betrachtet mich argw\u00f6hnisch. Gnak Prak zum Dank, stand ich nun nicht mit leeren H\u00e4nden da. LiNeer nahm das Geschenk an, doch brach das keines&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/chroniken.whenua.at\/del-nolo\/spinnen-und-ihre-maenner\/\">Continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"ppma_author":[29],"class_list":["post-1038","post","type-post","status-publish","format-standard","hentry","category-jahresfest-217"],"authors":[{"term_id":29,"user_id":2,"is_guest":0,"slug":"lyanna","display_name":"Lyanna del Nolo","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/69d1d8256126cbedb37057beca5363303685a1f9d047a9b7d31bcf99f00788c5?s=96&d=mm&r=g","author_category":"","first_name":"Lyanna","last_name":"del Nolo","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":1,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/1038\/revisions"}],"predecessor-version":[{"id":1040,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/posts\/1038\/revisions\/1040"}],"wp:attachment":[{"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/tags?post=1038"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/chroniken.whenua.at\/del-nolo\/wp-json\/wp\/v2\/ppma_author?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}